{"id":2078,"count":1,"description":"","link":"https:\/\/blogfca.pucminas.br\/colab\/tag\/donald-trump\/","name":"Donald Trump","slug":"donald-trump","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivos Donald Trump - Colab<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogfca.pucminas.br\/colab\/tag\/donald-trump\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Donald Trump - Colab\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogfca.pucminas.br\/colab\/tag\/donald-trump\/\" \/>\n<meta property=\"og:site_name\" content=\"Colab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@colabpucminas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/tag\\\/donald-trump\\\/\",\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/tag\\\/donald-trump\\\/\",\"name\":\"Arquivos Donald Trump - Colab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/tag\\\/donald-trump\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/tag\\\/donald-trump\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Donald Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#website\",\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/\",\"name\":\"Colab\",\"description\":\"Experimenta\u00e7\u00e3o, conte\u00fado e colabora\u00e7\u00e3o em Jornalismo Digital\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#organization\",\"name\":\"Colab :: Laborat\u00f3rio de Comunica\u00e7\u00e3o Digital da FCA \\\/ PUC Minas\",\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Avatar-Colab.jpg\",\"contentUrl\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Avatar-Colab.jpg\",\"width\":1682,\"height\":1682,\"caption\":\"Colab :: Laborat\u00f3rio de Comunica\u00e7\u00e3o Digital da FCA \\\/ PUC Minas\"},\"image\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/colabpucminas\",\"https:\\\/\\\/x.com\\\/colabpucminas\",\"https:\\\/\\\/www.instagram.com\\\/colabpucminas\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/colab-puc-minas\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC14mKIqnnGCOgVr4DG6FPkA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Donald Trump - Colab","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogfca.pucminas.br\/colab\/tag\/donald-trump\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos Donald Trump - Colab","og_url":"https:\/\/blogfca.pucminas.br\/colab\/tag\/donald-trump\/","og_site_name":"Colab","twitter_card":"summary_large_image","twitter_site":"@colabpucminas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogfca.pucminas.br\/colab\/tag\/donald-trump\/","url":"https:\/\/blogfca.pucminas.br\/colab\/tag\/donald-trump\/","name":"Arquivos Donald Trump - Colab","isPartOf":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/#website"},"breadcrumb":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/tag\/donald-trump\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/blogfca.pucminas.br\/colab\/tag\/donald-trump\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blogfca.pucminas.br\/colab\/"},{"@type":"ListItem","position":2,"name":"Donald Trump"}]},{"@type":"WebSite","@id":"https:\/\/blogfca.pucminas.br\/colab\/#website","url":"https:\/\/blogfca.pucminas.br\/colab\/","name":"Colab","description":"Experimenta\u00e7\u00e3o, conte\u00fado e colabora\u00e7\u00e3o em Jornalismo Digital","publisher":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogfca.pucminas.br\/colab\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blogfca.pucminas.br\/colab\/#organization","name":"Colab :: Laborat\u00f3rio de Comunica\u00e7\u00e3o Digital da FCA \/ PUC Minas","url":"https:\/\/blogfca.pucminas.br\/colab\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogfca.pucminas.br\/colab\/#\/schema\/logo\/image\/","url":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2020\/03\/Avatar-Colab.jpg","contentUrl":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2020\/03\/Avatar-Colab.jpg","width":1682,"height":1682,"caption":"Colab :: Laborat\u00f3rio de Comunica\u00e7\u00e3o Digital da FCA \/ PUC Minas"},"image":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/colabpucminas","https:\/\/x.com\/colabpucminas","https:\/\/www.instagram.com\/colabpucminas\/","https:\/\/www.linkedin.com\/company\/colab-puc-minas","https:\/\/www.youtube.com\/channel\/UC14mKIqnnGCOgVr4DG6FPkA"]}]}},"_links":{"self":[{"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/tags\/2078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/posts?tags=2078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}