{"id":24539,"date":"2025-09-25T15:44:06","date_gmt":"2025-09-25T18:44:06","guid":{"rendered":"https:\/\/blogfca.pucminas.br\/colab\/?p=24539"},"modified":"2025-10-08T21:39:44","modified_gmt":"2025-10-09T00:39:44","slug":"anonimato-alimenta-discurso-de-odio-nas-midias-sociais","status":"publish","type":"post","link":"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/","title":{"rendered":"Anonimato alimenta discurso de \u00f3dio nas m\u00eddias sociais"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Atacar o saber, queimar livros, destruir bibliotecas, atear fogo em Roma. O fascismo a produ\u00e7\u00e3o da mentira como solu\u00e7\u00e3o para a crise do capital\u201d &#8211;<a href=\"https:\/\/www.youtube.com\/watch?v=mmBywA4LmKg\" target=\"_blank\" rel=\"noreferrer noopener\"> <strong>Darcy Ribeiro, 1995 na Universidade de Bras\u00edlia (UnB).<\/strong><\/a><\/p>\n<\/blockquote>\n\n\n\n<p>A pol\u00edtica deixou de ser um t\u00f3pico de debate exclusivo dos meios de comunica\u00e7\u00e3o tradicionais como r\u00e1dio e televis\u00e3o, e passou a ser majoritariamente discutido nas m\u00eddias sociais. Desde a <a href=\"https:\/\/blogfca.pucminas.br\/colab\/category\/politica\/\" target=\"_blank\" rel=\"noreferrer noopener\">candidatura do ex-presidente Jair Bolsonaro<\/a>, em 2018, o Brasil vive um momento cr\u00edtico de polariza\u00e7\u00e3o. A busca por uma identidade extremista tem se tornado cada vez mais evidente entre adolescentes e jovens adultos com o crescimento exponencial do uso das m\u00eddias sociais.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-dominant-color=\"957e7b\" data-has-transparency=\"false\" style=\"--dominant-color: #957e7b;\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"678\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Entrega_do_Titulo_de_Doutor_Honoris_Causa_para_Darcy_Ribeiro-1024x678.webp\" alt=\"\" class=\"wp-image-24543 not-transparent\" srcset=\"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Entrega_do_Titulo_de_Doutor_Honoris_Causa_para_Darcy_Ribeiro-1024x678.webp 1024w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Entrega_do_Titulo_de_Doutor_Honoris_Causa_para_Darcy_Ribeiro-300x199.webp 300w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Entrega_do_Titulo_de_Doutor_Honoris_Causa_para_Darcy_Ribeiro-768x509.webp 768w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Entrega_do_Titulo_de_Doutor_Honoris_Causa_para_Darcy_Ribeiro-1536x1018.webp 1536w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Entrega_do_Titulo_de_Doutor_Honoris_Causa_para_Darcy_Ribeiro-370x245.webp 370w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Entrega_do_Titulo_de_Doutor_Honoris_Causa_para_Darcy_Ribeiro-270x179.webp 270w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Entrega_do_Titulo_de_Doutor_Honoris_Causa_para_Darcy_Ribeiro-570x378.webp 570w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Entrega_do_Titulo_de_Doutor_Honoris_Causa_para_Darcy_Ribeiro-740x490.webp 740w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Entrega_do_Titulo_de_Doutor_Honoris_Causa_para_Darcy_Ribeiro-150x99.webp 150w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Entrega_do_Titulo_de_Doutor_Honoris_Causa_para_Darcy_Ribeiro.webp 1674w\" \/><figcaption class=\"wp-element-caption\">Intelectual brasileiro participa de cerim\u00f4nia oficial e recebe homenagem p\u00fablica.   Arquivo Central da Universidade de Bras\u00edlia\n<\/figcaption><\/figure>\n\n\n\n<p>Para a gera\u00e7\u00e3o atual, as plataformas sociais s\u00e3o os principais canais de comunica\u00e7\u00e3o para se integrar sobre os acontecimentos da pol\u00edtica e para expressar opini\u00f5es. A <a href=\"https:\/\/centralperiferica.eca.usp.br\/redes-sociais-e-o-modo-como-jovens-entendem-a-politica\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>revista Central Perif\u00e9rica da USP<\/strong><\/a>, analisou e estudou o assunto, mostrando que as redes sociais se tornaram \u201cespa\u00e7os de discuss\u00e3o pol\u00edtica, criando um debate em que muitos podem dar sua opini\u00e3o.\u201d Esse acesso direto e sem intermedi\u00e1rios permite que as pessoas formem opini\u00f5es, participem de debates e, em v\u00e1rios casos, se organizem para protestos e campanhas.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Isso, de certa forma, alimenta esses discursos [\u00f3dio], esses posicionamentos nas m\u00eddias sociais<\/p>\n<\/blockquote>\n\n\n\n<p>A insatisfa\u00e7\u00e3o dos jovens muitas vezes s\u00e3o colocadas nas timelines das m\u00eddias sociais como forma de protestar seus pensamentos, ideologias e fundamentos. Por\u00e9m, o discurso de \u00f3dio promovido pela oposi\u00e7\u00e3o dos governos recorrentes, a falta de responsabiliza\u00e7\u00e3o do que \u00e9 dito e o anonimato oferecido pela internet s\u00e3o v\u00e1rias das caracter\u00edsticas negativas presentes nas&nbsp; m\u00eddias sociais, conforme defende Homero Nunes historiador, soci\u00f3logo e professor:<br><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>N\u00f3s estamos dilu\u00eddos em uma quantidade t\u00e3o grande de pessoas que frequentam essas redes sociais que a sensa\u00e7\u00e3o de anonimato \u00e9 muito grande. [&#8230;] Isso, de certa forma, alimenta esses discursos, esses posicionamentos nas redes sociais.\u201d Homero Nunes.<br><\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O fen\u00f4meno Bolsonaro&nbsp;<\/strong><br><\/h2>\n\n\n\n<p>O ex-presidente Jair Bolsonaro e ex-deputado federal do Rio de Janeiro durante 7 mandatos, usou de estrat\u00e9gias que o colocaram no cargo pol\u00edtico mais alto do pa\u00eds. Para Homero, Bolsonaro usou de discursos problem\u00e1ticos e da vulnerabilidade da oposi\u00e7\u00e3o para conseguir visibilidade, e assim, tornar-se uma pessoa c\u00e9lebre ao participar de&nbsp; programas de TV como Super Pop e&nbsp; P\u00e2nico.<br><br>As elei\u00e7\u00f5es presidenciais de 2018 no Brasil s\u00e3o frequentemente citadas como um ponto de inflex\u00e3o na pol\u00edtica nacional, no qual a estrat\u00e9gia digital provou ser um fator decisivo. O material da <a href=\"https:\/\/centralperiferica.eca.usp.br\/redes-sociais-e-o-modo-como-jovens-entendem-a-politica\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Central Perif\u00e9rica da USP<\/strong><\/a> aponta que candidatos, com pouca ou nenhuma exposi\u00e7\u00e3o em r\u00e1dio e televis\u00e3o, tradicionalmente considerados elementos cruciais para o sucesso eleitoral, conseguiram ser eleitos, demonstrando a maturidade do ecossistema digital como alternativa vi\u00e1vel. A regulamenta\u00e7\u00e3o da propaganda eleitoral paga na internet, conhecida como impulsionamento, tamb\u00e9m contribuiu para essa mudan\u00e7a, permitindo que campanhas com menos recursos financeiros na m\u00eddia tradicional alcan\u00e7assem um grande n\u00famero de eleitores.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-dominant-color=\"938d8e\" data-has-transparency=\"false\" style=\"--dominant-color: #938d8e;\" loading=\"lazy\" decoding=\"async\" width=\"630\" height=\"420\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" src=\"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/bolsonaro-vagabundo-Zuma-Press.webp\" alt=\"\" class=\"wp-image-24550 not-transparent\" srcset=\"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/bolsonaro-vagabundo-Zuma-Press.webp 630w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/bolsonaro-vagabundo-Zuma-Press-300x200.webp 300w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/bolsonaro-vagabundo-Zuma-Press-370x247.webp 370w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/bolsonaro-vagabundo-Zuma-Press-270x180.webp 270w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/bolsonaro-vagabundo-Zuma-Press-570x380.webp 570w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/bolsonaro-vagabundo-Zuma-Press-150x100.webp 150w\" \/><figcaption class=\"wp-element-caption\">Jair Bolsonaro durante pronunciamento oficial em Bras\u00edlia. &#8211; Zuma Press<\/figcaption><\/figure>\n\n\n\n<p><a href=\"https:\/\/repositorio.cepelin.org\/index.php\/repositorioppglintesesdissertaco\/article\/download\/219\/207\/284\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Um estudo feito por Marina Bichara Faria Coelho, formada na Escola Brasileira de Administra\u00e7\u00e3o P\u00fablica e de Empresas<\/strong><\/a><strong>,<\/strong> analisou a campanha de 2018 do ex-presidente Jair Bolsonaro no Twitter, oferecendo uma vis\u00e3o detalhada de como as redes foram usadas de forma estrat\u00e9gica. O estudo categoriza as t\u00e1ticas empregadas: gerar engajamento para ampliar o alcance e as intera\u00e7\u00f5es, utilizar a campanha negativa para se diferenciar dos advers\u00e1rios e divulgar propostas e posicionamentos.<\/p>\n\n\n\n<p>Uma an\u00e1lise da Ag\u00eancia P\u00fablica tamb\u00e9m sugere que as a\u00e7\u00f5es de Jair Bolsonaro se baseiam em um &#8220;manual&#8221; que replica a estrat\u00e9gia de Donald Trump nos Estados Unidos. A articula\u00e7\u00e3o \u00e9 descrita como transnacional e deliberada, exemplificada pela rela\u00e7\u00e3o entre o filho do ex-presidente, Eduardo Bolsonaro, e o ide\u00f3logo da ultradireita americana Steve Bannon.&nbsp;&nbsp;<\/p>\n\n\n\n<p>O discurso \u00e9 um componente central das estrat\u00e9gias de Trump e Bolsonaro. Comentadores apontam que o discurso &#8220;agressivo&#8221; de Trump tem se associado ao aumento de sua popularidade.<\/p>\n\n\n\n<p>&nbsp;A hostilidade contra a imprensa \u00e9 uma t\u00e1tica central. O ex-presidente americano e o brasileiro ecoaram, segundo o historiador Federico Finchelstein, em conversa com o no <em>The Intercept Brasil<\/em>, a avers\u00e3o nazista \u00e0 &#8220;imprensa liberal&#8221;, acusando a m\u00eddia de ser &#8220;desonesta&#8221; e &#8220;hostil&#8221;. O objetivo dessa estrat\u00e9gia \u00e9 descredibilizar a informa\u00e7\u00e3o verificada, com os eleitores se tornando dependentes do ecossistema de desinforma\u00e7\u00e3o criado pelos l\u00edderes.&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/brasil.elpais.com\/brasil\/2020-08-20\/os-lacos-do-cla-bolsonaro-com-steve-bannon.html\" target=\"_blank\" rel=\"noreferrer noopener\">A rela\u00e7\u00e3o entre Eduardo Bolsonaro e Steve Bannon formalizou a transfer\u00eancia de estrat\u00e9gias da ultradireita americana para a brasileira.<\/a> A estrat\u00e9gia visa manter um &#8220;estado de tens\u00e3o permanente&#8221; p\u00f3s-eleitoral que pode erodir a confian\u00e7a nas institui\u00e7\u00f5es democr\u00e1ticas. A rela\u00e7\u00e3o entre Steve Bannon e a fam\u00edlia Bolsonaro solidificou-se em 2018, ano da elei\u00e7\u00e3o de Jair Bolsonaro \u00e0 presid\u00eancia. Em agosto daquele ano, Eduardo Bolsonaro conheceu pessoalmente o estrategista em Nova York, descrevendo a conversa como uma &#8220;uni\u00e3o de for\u00e7as contra o marxismo cultural&#8221;. Para Bannon, o contato com o filho do ent\u00e3o candidato representava o &#8220;coroamento de um plano&#8221; que ele concebera h\u00e1 anos: o de ter influ\u00eancia direta sobre a presid\u00eancia do Brasil.&nbsp;<\/p>\n\n\n\n<p>No estudo \u201cA ideologia de Steve Bannon\u201d, <a href=\"https:\/\/www.scielo.br\/j\/sant\/a\/bLLTnxyrMppVhCXwChrm6rN\/?format=html&amp;lang=pt\" target=\"_blank\" rel=\"noreferrer noopener\">Jeffrey Alexander<\/a>, explora um epis\u00f3dio pol\u00edtico de extrema import\u00e2ncia para o cen\u00e1rio brasileiro. A &#8220;guerra cultural&#8221; (termo citado na obra) \u00e9 uma estrat\u00e9gia de mobiliza\u00e7\u00e3o e polariza\u00e7\u00e3o, que utiliza ret\u00f3ricas fortes e simplifica\u00e7\u00f5es para criar espa\u00e7os de batalha nas redes sociais.<sup>&nbsp; <\/sup>A disputa se d\u00e1 no campo ideol\u00f3gico, envolvendo valores, cren\u00e7as e normas, com o objetivo de minar consensos e legitimar a viol\u00eancia pol\u00edtica.<sup> <\/sup>A base ideol\u00f3gica dessa estrat\u00e9gia, particularmente na extrema-direita, \u00e9 a teoria da conspira\u00e7\u00e3o antissemita do &#8220;marxismo cultural,&#8221; que alega que for\u00e7as de esquerda secretamente conspiram para destruir os valores ocidentais e crist\u00e3os<\/p>\n\n\n\n<p>A ret\u00f3rica de Bannon demonstra a adaptabilidade da estrat\u00e9gia. Ap\u00f3s a derrota eleitoral, o foco mudou da deslegitima\u00e7\u00e3o do voto para a legitima\u00e7\u00e3o da revolta. Ao chamar os protestos de &#8220;Primavera Brasileira&#8221;, ele ofereceu aos apoiadores de Bolsonaro uma narrativa global e her\u00f3ica para justificar suas a\u00e7\u00f5es, dando-lhes um prop\u00f3sito maior do que a simples derrota eleitoral. Essa ret\u00f3rica serviu como uma &#8220;licen\u00e7a de a\u00e7\u00e3o&#8221; para os radicais. Ao enquadrar o movimento como parte de uma &#8220;guerra&#8221; global, ele reduziu a percep\u00e7\u00e3o do risco das a\u00e7\u00f5es antidemocr\u00e1ticas e insuflou a &#8220;revolu\u00e7\u00e3o fantasiosa&#8221; que culminou em 8 de janeiro.<\/p>\n\n\n\n<p>Uma pesquisa da Universidade do Sul da Fl\u00f3rida demonstrou que parte das publica\u00e7\u00f5es feitas nas redes sociais antes e durante os ataques <a href=\"https:\/\/www.cnnbrasil.com.br\/politica\/perfis-nos-eua-insuflaram-redes-e-estimularam-ataques-no-8-de-janeiro-diz-pesquisa\/\" target=\"_blank\" rel=\"noreferrer noopener\">de 8 de janeiro de 2023<\/a>&nbsp; veio de usu\u00e1rios registrados nos Estados Unidos, especialmente em Orlando e Miami.<sup>&nbsp; <\/sup>O estudo concluiu que redes de desinforma\u00e7\u00e3o para al\u00e9m das fronteiras de um pa\u00eds tra\u00e7aram um paralelo claro entre o que aconteceu em Bras\u00edlia e a invas\u00e3o do Capit\u00f3lio americano em 6 de janeiro de 2021.<\/p>\n\n\n\n<p>Ap\u00f3s os eventos de 8 de janeiro e as subsequentes condena\u00e7\u00f5es, a pauta da anistia ganhou relev\u00e2ncia no <a href=\"https:\/\/www12.senado.leg.br\/ecidadania\/visualizacaomateria?id=160575\" target=\"_blank\" rel=\"noreferrer noopener\">Congresso Nacional.<\/a> A C\u00e2mara dos Deputados aprovou a urg\u00eancia do projeto que visa conceder anistia aos acusados e condenados pelos atos, um movimento apoiado por parlamentares alinhados a Jair Bolsonaro. O projeto, PL 5064\/2023, de autoria do senador Hamilton Mour\u00e3o, busca anistiar aqueles envolvidos nos crimes definidos nos artigos 359-L e 359-M do C\u00f3digo Penal, relacionados aos eventos em Bras\u00edlia. No debate, o senador Fl\u00e1vio Bolsonaro defendeu uma anistia &#8220;ampla, geral, irrestrita e imediata&#8221;. O tema se tornou um ponto de alta polariza\u00e7\u00e3o, com manifesta\u00e7\u00f5es de apoiadores defendendo a anistia e a oposi\u00e7\u00e3o se posicionando contra.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>A nova gera\u00e7\u00e3o pol\u00edtica: vulnerabilidade e busca por identidade<\/strong> a partir do discurso de \u00f3dio<\/h2>\n\n\n\n<p>A forma\u00e7\u00e3o da identidade jovem passa hoje pela ado\u00e7\u00e3o de narrativas coletivas que, muitas vezes, fornecem explica\u00e7\u00f5es simples para problemas que s\u00e3o considerados complexos. Entre essas narrativas, os ideais extremistas ganham cada vez mais for\u00e7a. Um conjunto de cren\u00e7as autorit\u00e1rias, ultranacionalistas, e hier\u00e1rquicas que remetem direta ou indiretamente&nbsp; ao facismo e ao nazismo. Essa atra\u00e7\u00e3o n\u00e3o se d\u00e1 apenas pela est\u00e9tica visual, mas por discursos que prometem ordem, pureza e um \u201csentido de pertencimento\u201d capaz de preencher vazios existenciais.<br><\/p>\n\n\n\n<p>Segundo Vilma dos Santos, psicologa comportamental, a rebeldia comum \u00e0 adolesc\u00eancia \u00e9 um terreno f\u00e9rtil para a ades\u00e3o a id\u00e9ias radicais, e os algoritmos potencializam essa inclina\u00e7\u00e3o. A l\u00f3gica da radicaliza\u00e7\u00e3o migra do virtual para o cotidiano, afetando diretamente a conviv\u00eancia e o ambiente escolar, \u00e0 medida que os jovens expressam ativamente as posi\u00e7\u00f5es que consomem online.<\/p>\n\n\n\n<p>Al\u00e9m disso, a coopta\u00e7\u00e3o da juventude por meio do ambiente digital ultrapassa o simples, consumo de conte\u00fados. em entrevista ao portal <a href=\"https:\/\/sicnoticias.pt\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sic Not\u00edcias<\/a> a Filinto Lima, presidente da Associa\u00e7\u00e3o Nacional de Diretores de Agrupamentos e Escolas P\u00fablicas, ressalta que a converg\u00eancia entre os&nbsp; jovens com as posi\u00e7\u00f5es extremistas \u00e9 uma tend\u00eancia que j\u00e1 se poderia observar nas escolas, n\u00e3o estando mais &#8220;circunscrito \u00e0s redes sociais&#8221;.&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/sicnoticias.pt\/pais\/2025-06-01-educadores-sentem-se-numa-competicao-desleal-com-as-redes-sociais-para-formar-jovens-78eea729\" target=\"_blank\" rel=\"noreferrer noopener\">Especialistas em educa\u00e7\u00e3o, como Filinto Lima, e Manuel Pereira, presidente da Associa\u00e7\u00e3o Nacional de Dirigentes Escolares (ANDE)<\/a>, apontaram uma competi\u00e7\u00e3o quase que desleal entre as institui\u00e7\u00f5es de ensino e as m\u00eddias sociais pela forma\u00e7\u00e3o de identidade dos jovens. Plataformas como TikTok, X e Instagram s\u00e3o apontadas como os principais espa\u00e7os de lazer e consumo de informa\u00e7\u00e3o para essa faixa et\u00e1ria, uma din\u00e2mica que tem contribu\u00eddo para o avan\u00e7o de discursos da extrema-direita.&nbsp;<\/p>\n\n\n\n<p>Na Europa, por exemplo, uma pesquisa revelou que <a href=\"https:\/\/www.youtube.com\/watch?v=z6Qc6QYARQE\" target=\"_blank\" rel=\"noreferrer noopener\">46% dos eurodeputados da extrema-direita na Fran\u00e7a, It\u00e1lia e Alemanha t\u00eam presen\u00e7a no TikTok.<\/a> Hoje, no Brasil, o YouTube tem um papel central,<a href=\"https:\/\/www.youtube.com\/watch?v=GLiaEGsmWMQ\" target=\"_blank\" rel=\"noreferrer noopener\"> sendo que em 2018 foi notada a tend\u00eancia da plataforma em recomendar canais de extrema-direita e que defendiam pr\u00e1ticas de desinforma\u00e7\u00e3o.&nbsp;&nbsp;<\/a><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-dominant-color=\"a2014a\" data-has-transparency=\"false\" style=\"--dominant-color: #a2014a;\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"24554\" src=\"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Rede-Social-Tik-Tok.webp\" alt=\"\" class=\"wp-image-24554 not-transparent\" srcset=\"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Rede-Social-Tik-Tok.webp 1024w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Rede-Social-Tik-Tok-300x200.webp 300w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Rede-Social-Tik-Tok-768x512.webp 768w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Rede-Social-Tik-Tok-370x247.webp 370w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Rede-Social-Tik-Tok-270x180.webp 270w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Rede-Social-Tik-Tok-570x380.webp 570w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Rede-Social-Tik-Tok-740x494.webp 740w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Rede-Social-Tik-Tok-150x100.webp 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Aplicativo TikTok aberto em celular contra fundo colorido &#8211; Solen Feyissa<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p>O engajamento da extrema-direita entre os jovens est\u00e1 associado, em parte, ao funcionamento das plataformas digitais.<a href=\"https:\/\/veja.abril.com.br\/coluna\/maquiavel\/por-que-o-eleitorado-jovem-esta-aderindo-a-direita-radical-no-brasil\/\" target=\"_blank\" rel=\"noreferrer noopener\"> A pesquisa de Renato Meirelles do Instituto Locomotiva<\/a> destaca que a l\u00f3gica dos algoritmos se baseia na pol\u00eamica e &#8220;retroalimenta um pensamento mais radicalizado&#8221;. Conte\u00fados com pautas contra o feminismo, a comunidade LGBTQIA+ e imigrantes t\u00eam alcan\u00e7ado milh\u00f5es de visualiza\u00e7\u00f5es e likes. &nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cAs democracias enfrentam um dilema urgente: avan\u00e7ar na regulamenta\u00e7\u00e3o e controle da Intelig\u00eancia Artificial com coragem e efic\u00e1cia, ou continuar a responder tardiamente, enquanto uma nova gera\u00e7\u00e3o \u00e9 seduzida por m\u00e1quinas que oferecem sentido, perten\u00e7a e reden\u00e7\u00e3o&#8230; ao servi\u00e7o do \u00f3dio.\u201d <a href=\"https:\/\/expresso.pt\/autores\/2025-04-23-diogo-alexandre-carapinha-e8425e6c\" target=\"_blank\" rel=\"noreferrer noopener\">Diogo Alexandre Carapinha, Consultor e sub-coordenador do VisionWare Threat Intelligence Center<\/a><\/p>\n<\/blockquote>\n\n\n\n<p>A crescente das intelig\u00eancia artificiais&nbsp; tamb\u00e9m tem mostrado um papel crucial neste processo, multiplicando e automatizando discursos. Diogo Alexandre Carapinha, consultor e sub-coordenador do VisionWare Threat Intelligence Center, f\u00f3runs como o 4chan e o Telegram abrigam bots treinados com material neonazista e teorias da conspira\u00e7\u00e3o, que refor\u00e7am bolhas de informa\u00e7\u00e3o e podem radicalizar grupos espec\u00edficos. Atrav\u00e9s do que foi dito por Diogo em conversa com Extra, a comunidade <em>incel<\/em>, por exemplo, \u00e9 alvo de um &#8220;algoritmo da misoginia&#8221; em plataformas como Reddit e Discord, onde a IA automatiza e amplifica conte\u00fados mis\u00f3ginos, transformando a comunidade em uma &#8220;amea\u00e7a mais sofisticada e menos vis\u00edvel&#8221;.&nbsp;<\/p>\n\n\n\n<p>A popularidade de influenciadores digitais, que t\u00eam o apoio de jovens, principalmente rapazes , \u00e9 um fator relevante. A visibilidade de suas mensagens contribui para a legitima\u00e7\u00e3o de determinados tipos de conte\u00fado. No Brasil, pol\u00edticos como Fernando Holiday, Kim Kataguiri e Arthur Mam\u00e3e Falei, que ascenderam no meio digital, s\u00e3o exemplos dessa din\u00e2mica. A rede de apoio a Jair Bolsonaro, em particular, utilizou o YouTube como a plataforma mais recomendada at\u00e9 2020, evidenciando a ado\u00e7\u00e3o de uma &#8220;gram\u00e1tica audiovisual&#8221; para se comunicar com sua base de apoiadores.&nbsp;&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/www.camara.leg.br\/noticias\/943540-arthur-lira-repreende-deputado-nikolas-ferreira-por-discurso-contra-mulheres-trans\/?utm_source=chatgpt.com\" target=\"_blank\" rel=\"noreferrer noopener\">Nikolas Ferreira<\/a>&nbsp; se tornou, de forma extremamente r\u00e1pida, uma figura central na direita pol\u00edtica. Al\u00e9m da presen\u00e7a massiva nas redes sociais, que o projetaram como um dos deputados mais midiatizados,&nbsp; ele tamb\u00e9m acumula epis\u00f3dios p\u00fablicos que ilustram uma estrat\u00e9gia discursiva agressiva e de confronta\u00e7\u00e3o. Em plen\u00e1rio e em v\u00eddeos virais, Nikolas j\u00e1 foi repreendido por declara\u00e7\u00f5es contra parlamentares trans e sofreu den\u00fancias e processos relacionados a discursos considerados transf\u00f3bicos e racistas, que se desdobraram em investiga\u00e7\u00f5es, a\u00e7\u00f5es judiciais e cr\u00edticas, feitas pelo presidente da C\u00e2mara de Deputados Arthur Lira. Essas movimenta\u00e7\u00f5es n\u00e3o s\u00e3o apenas epis\u00f3dios isolados, e tamb\u00e9m mostram como um parlamentar usa a exposi\u00e7\u00e3o online para moldar pautas e mobilizar apoio.<\/p>\n\n\n\n<p>Ao mesmo tempo, a trajet\u00f3ria institucional do deputado revela um fen\u00f4meno quase que paradoxal. Eleito e com cargos importantes, inclusive a presid\u00eancia de uma comiss\u00e3o da C\u00e2mara, Nikolas opera tanto nas arenas formais da pol\u00edtica quanto no ecossistema informal das plataformas digitais, onde campanhas e v\u00eddeos virais (como a cr\u00edtica a poss\u00edvel taxa\u00e7\u00e3o do Pix) ampliaram seu alcance e influ\u00eancia junto a parcelas significativas do eleitorado. Esse cruzamento entre a\u00e7\u00e3o parlamentar e desempenho midi\u00e1tico \u00e9 uma chave para entender por que figuras como ele conseguem impacto r\u00e1pido na opini\u00e3o p\u00fablica. <a href=\"https:\/\/www.camara.leg.br\/deputados\/209787?utm_source=chatgpt.com\" target=\"_blank\" rel=\"noreferrer noopener\">Portal da C\u00e2mara dos Deputados<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Discurso de \u00f3dio: contexto hist\u00f3rico\u00a0<\/strong><\/h2>\n\n\n\n<p>Thiago Lara, professor formando em hist\u00f3ria conta que os regimes nazista e fascista investiram na doutrina\u00e7\u00e3o da juventude. A Juventude Hitlerista (<em>Hitlerjugend<\/em>) e a Liga das Mo\u00e7as Alem\u00e3s (<em>Bund Deutscher M\u00e4del<\/em>) foram organiza\u00e7\u00f5es obrigat\u00f3rias para jovens de 10 a 18 anos na Alemanha Nazista a partir de 1939, com o objetivo de treinar crian\u00e7as e adolescentes nos interesses do regime. Na It\u00e1lia Fascista, a Opera Nazionale Balilla (ONB), estabelecida em 1926, era um &#8220;corpo moral&#8221; que visava a &#8220;educa\u00e7\u00e3o f\u00edsica e moral da juventude&#8221;, e a participa\u00e7\u00e3o, embora inicialmente volunt\u00e1ria, tornou-se compuls\u00f3ria.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-dominant-color=\"717171\" data-has-transparency=\"false\" style=\"--dominant-color: #717171;\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"544\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" src=\"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/hitler-mamando.webp\" alt=\"\" class=\"wp-image-24546 not-transparent\" srcset=\"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/hitler-mamando.webp 800w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/hitler-mamando-300x204.webp 300w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/hitler-mamando-768x522.webp 768w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/hitler-mamando-370x252.webp 370w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/hitler-mamando-270x184.webp 270w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/hitler-mamando-570x388.webp 570w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/hitler-mamando-740x503.webp 740w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/hitler-mamando-150x102.webp 150w\" \/><figcaption class=\"wp-element-caption\">Adolf Hitler faz sauda\u00e7\u00e3o nazista em ato p\u00fablico durante o regime nazista &#8211; Creative Commons<\/figcaption><\/figure>\n\n\n\n<p>No artigo <a href=\"https:\/\/www.redalyc.org\/pdf\/3847\/384779299003.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u201cA educa\u00e7\u00e3o na alemanha nazista e seu papel na modula\u00e7\u00e3o de ideias e comportamentos\u201d<\/a>, Cleri Aparecida Brandt e Jorge Lu\u00eds Mialhe contam como essas organiza\u00e7\u00f5es tinham como objetivo&nbsp; moldar as ideias e os comportamentos dos jovens. Os meninos eram preparados para serem soldados e futuros membros do Partido, enquanto as meninas eram ensinadas a serem esposas e m\u00e3es, com atividades focadas em tarefas dom\u00e9sticas e trabalho em equipe. Esses governos buscavam enfraquecer a influ\u00eancia dos pais e da Igreja, incentivando os jovens a relatar o que acontecia em suas escolas e fam\u00edlias aos seus l\u00edderes.&nbsp;&nbsp;<\/p>\n\n\n\n<p>A doutrina\u00e7\u00e3o era centralizada. Os jovens usavam os mesmos uniformes, cantavam as mesmas can\u00e7\u00f5es e participavam de atividades paramilitares. A propaganda nazista utilizou meios como r\u00e1dio, filmes, cartazes e livros, incluindo contos infantis como <em>Der Giftpilz<\/em> (&#8220;O Cogumelo Venenoso&#8221;), que ensinava o \u00f3dio antissemita, e livros did\u00e1ticos como <em>Rassenkunde des deutschen Volkes<\/em> (&#8220;Ci\u00eancia Racial do Povo Alem\u00e3o&#8221;). O fascismo italiano utilizou publica\u00e7\u00f5es como &#8220;O Tamburino da Juventude Italiana no Exterior&#8221; para &#8220;fascistizar os italianos emigrados e seus descendentes&#8221;.&nbsp;<br><br><strong>Compara\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>Ainda h\u00e1 um debate em curso sobre a aplica\u00e7\u00e3o do termo &#8220;fascismo&#8221; aos movimentos atuais. O jornalista <a href=\"https:\/\/www.youtube.com\/watch?v=z6Qc6QYARQE\" target=\"_blank\" rel=\"noreferrer noopener\">Wevergton Brito<\/a> argumenta que a moderna extrema-direita, encarnada por Donald Trump, \u00e9 o &#8220;fascismo do s\u00e9culo XXI&#8221; pois &#8220;re\u00fane todos os atributos essenciais que encontramos no fascismo cl\u00e1ssico&#8221;. Por outro lado, o historiador Enzo Traverso conforme explicado (&#8230;) o termo &#8220;p\u00f3s-fascismo&#8221;, destacando as particularidades e as transforma\u00e7\u00f5es em rela\u00e7\u00e3o ao fascismo hist\u00f3rico, como o fato de o capital financeiro n\u00e3o ter o mesmo tipo de apoio aos movimentos atuais como no passado.&nbsp;<br><br><em>Como as democracias morrem<\/em>, livro de Steven Levitsky e Daniel Ziblatt, conta que amea\u00e7as \u00e0 democracia frequentemente v\u00eam da eros\u00e3o de normas informais, sobretudo\u201d o abandono do compromisso com regras b\u00e1sicas de jogo democr\u00e1tico pelos pr\u00f3prios atores pol\u00edticos\u201d, e n\u00e3o apenas de golpes formais. Discursos que desacreditam institui\u00e7\u00f5es, normalizam desrespeito e incentivam a polariza\u00e7\u00e3o extrema s\u00e3o sinais de alerta, porque corroem mecanismos de conten\u00e7\u00e3o que mant\u00eam a conviv\u00eancia pol\u00edtica dentro de limites democr\u00e1ticos.&nbsp;<\/p>\n\n\n\n<p>No caso brasileiro, a combina\u00e7\u00e3o entre l\u00edderes que exploram rancores e um ecossistema digital que distribui conte\u00fado em alta velocidade cria exatamente o tipo de <a href=\"https:\/\/revista.drclas.harvard.edu\/how-democracies-die\/?utm_source=chatgpt.com\" target=\"_blank\" rel=\"noreferrer noopener\">\u201ceros\u00e3o pelas normas\u201d<\/a> descrita por Levitsky e Ziblatt: quando pol\u00edticos transformam a contesta\u00e7\u00e3o em deslegitima\u00e7\u00e3o sistem\u00e1tica (da imprensa, do Judici\u00e1rio, de advers\u00e1rios), isso amplia o espa\u00e7o para comportamentos anti cient\u00edficos e anti pluralistas.<\/p>\n\n\n\n<p>A principal ruptura reside no papel da tecnologia. O fascismo cl\u00e1ssico dependia de um controle centralizado do Estado e de organiza\u00e7\u00f5es compuls\u00f3rias para doutrinar a juventude, com a propaganda sendo vertical e unidirecional. A extrema-direita digital opera de forma descentralizada. A radicaliza\u00e7\u00e3o \u00e9 facilitada por algoritmos e influenciadores que atuam sem a necessidade de uma estrutura estatal formal. O engajamento \u00e9 descrito como &#8220;volunt\u00e1rio&#8221;, atra\u00eddo pelo &#8220;esp\u00edrito rebelde&#8221; e pela sensa\u00e7\u00e3o de pertencimento a um grupo. A pr\u00f3pria base, com o uso de memes e not\u00edcias falsas, se torna o meio de propaganda.&nbsp;&nbsp;<\/p>\n\n\n\n<p>As estrat\u00e9gias de propaganda e mobiliza\u00e7\u00e3o dos movimentos de extrema-direita contempor\u00e2neos apresentam paralelos com o fascismo cl\u00e1ssico: Lideran\u00e7a e &#8220;Mito&#8221;: O fascismo cl\u00e1ssico, com Mussolini e Hitler, constru\u00eda um &#8220;mito&#8221; em torno de um l\u00edder &#8220;salvador&#8221; , com a propaganda nazista usando a imagem de Hitler para construir uma f\u00e9 inabal\u00e1vel. Da mesma forma, Trump e Bolsonaro cultivam uma imagem messi\u00e2nica.&nbsp;&nbsp;<\/p>\n\n\n\n<p>O Observat\u00f3rio Nacional dos Direitos Humanos (ObservaDH) e a Safernet registraram um aumento nas den\u00fancias de crimes de \u00f3dio na internet no Brasil. Em 2022, foram registrados mais de 74 mil casos, o maior n\u00famero desde 2017. O per\u00edodo eleitoral, em particular, \u00e9 identificado como um &#8220;gatilho&#8221; para o crescimento do engajamento com esse tipo de conte\u00fado, uma tend\u00eancia observada desde 2018.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-dominant-color=\"595959\" data-has-transparency=\"false\" style=\"--dominant-color: #595959;\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"282\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" data-id=\"24553\" src=\"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/cyber-crime-1-1024x282.webp\" alt=\"\" class=\"wp-image-24553 not-transparent\" srcset=\"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/cyber-crime-1-1024x282.webp 1024w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/cyber-crime-1-300x83.webp 300w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/cyber-crime-1-768x211.webp 768w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/cyber-crime-1-1536x422.webp 1536w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/cyber-crime-1-370x102.webp 370w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/cyber-crime-1-270x74.webp 270w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/cyber-crime-1-570x157.webp 570w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/cyber-crime-1-740x204.webp 740w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/cyber-crime-1-150x41.webp 150w, https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/cyber-crime-1.webp 1920w\" \/><figcaption class=\"wp-element-caption\">Atividades digitais em destaque em imagem ilustrativa de seguran\u00e7a cibern\u00e9tica &#8211; CreativeCommons<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p>O relat\u00f3rio do MDHC indica a vulnerabilidade de diversos grupos, como mulheres, pessoas negras, LGBTQIA+ e jovens, a atos extremistas. O documento sugere a implementa\u00e7\u00e3o de pol\u00edticas p\u00fablicas de &#8220;educa\u00e7\u00e3o midi\u00e1tica&#8221; e a responsabiliza\u00e7\u00e3o de &#8220;superspreaders&#8221; e &#8220;fiadores do \u00f3dio&#8221;.&nbsp;&nbsp;<\/p>\n\n\n\n<p>A pesquisa indica que a extrema-direita contempor\u00e2nea adaptou t\u00e1ticas hist\u00f3ricas de doutrina\u00e7\u00e3o da juventude para a era digital. A principal mudan\u00e7a observada \u00e9 a transi\u00e7\u00e3o de organiza\u00e7\u00f5es controladas pelo Estado para redes digitais descentralizadas, onde algoritmos e influenciadores desempenham um papel central na dissemina\u00e7\u00e3o de discursos. O engajamento com a juventude \u00e9 facilitado por uma narrativa que, segundo analistas, utiliza o humor e o sentimento &#8220;antissistema&#8221; para atrair e manter seguidores. Essa an\u00e1lise comparativa demonstra a evolu\u00e7\u00e3o das estrat\u00e9gias de mobiliza\u00e7\u00e3o de massas, que hoje se baseiam na l\u00f3gica das plataformas digitais para alcan\u00e7ar e influenciar novos p\u00fablicos.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>LEIA TAMB\u00c9M: <a href=\"https:\/\/blogfca.pucminas.br\/colab\/efeito-trump-os-impactos-da-vitoria-na-vida-dos-imigrantes\/\" target=\"_blank\" rel=\"noreferrer noopener\">EFEITO TRUMP: OS IMPACTOS DO DISCURO ANTI-IMIGRA\u00c7\u00c3O <\/a><\/p><\/blockquote><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elei\u00e7\u00e3o de 2018 marcou virada da pol\u00edtica <\/p>\n","protected":false},"author":115,"featured_media":24557,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[7,11],"tags":[628,2647,587,1173,1171,483,2649,2648],"class_list":["post-24539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eleicoes","category-politica","tag-bolsonaro","tag-historia-2","tag-instagram","tag-juventude","tag-politica-2","tag-redes-sociais","tag-tik-tok","tag-twitter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anonimato alimenta discurso de \u00f3dio nas m\u00eddias sociais - Colab<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anonimato alimenta discurso de \u00f3dio nas m\u00eddias sociais - Colab\" \/>\n<meta property=\"og:description\" content=\"Elei\u00e7\u00e3o de 2018 marcou virada da pol\u00edtica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/\" \/>\n<meta property=\"og:site_name\" content=\"Colab\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/colabpucminas\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-25T18:44:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T00:39:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Adobe-Express-file.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1296\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yago Rabelo Marques\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@colabpucminas\" \/>\n<meta name=\"twitter:site\" content=\"@colabpucminas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yago Rabelo Marques\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\\\/\"},\"author\":{\"name\":\"Yago Rabelo Marques\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#\\\/schema\\\/person\\\/86585f5b53a3550279327e4c1d56bac9\"},\"headline\":\"Anonimato alimenta discurso de \u00f3dio nas m\u00eddias sociais\",\"datePublished\":\"2025-09-25T18:44:06+00:00\",\"dateModified\":\"2025-10-09T00:39:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\\\/\"},\"wordCount\":3370,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Adobe-Express-file.webp\",\"keywords\":[\"bolsonaro\",\"historia\",\"Instagram\",\"juventude\",\"politica\",\"Redes sociais\",\"tik tok\",\"twitter\"],\"articleSection\":[\"Elei\u00e7\u00f5es\",\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\\\/\",\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\\\/\",\"name\":\"Anonimato alimenta discurso de \u00f3dio nas m\u00eddias sociais - Colab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Adobe-Express-file.webp\",\"datePublished\":\"2025-09-25T18:44:06+00:00\",\"dateModified\":\"2025-10-09T00:39:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Adobe-Express-file.webp\",\"contentUrl\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Adobe-Express-file.webp\",\"width\":1296,\"height\":675,\"caption\":\"Manifestante segura cartaz com a mensagem \u201cNo Hate\u201d durante protesto - Tim Pierce\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anonimato alimenta discurso de \u00f3dio nas m\u00eddias sociais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#website\",\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/\",\"name\":\"Colab\",\"description\":\"Experimenta\u00e7\u00e3o, conte\u00fado e colabora\u00e7\u00e3o em Jornalismo Digital\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#organization\",\"name\":\"Colab :: Laborat\u00f3rio de Comunica\u00e7\u00e3o Digital da FCA \\\/ PUC Minas\",\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Avatar-Colab.jpg\",\"contentUrl\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Avatar-Colab.jpg\",\"width\":1682,\"height\":1682,\"caption\":\"Colab :: Laborat\u00f3rio de Comunica\u00e7\u00e3o Digital da FCA \\\/ PUC Minas\"},\"image\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/colabpucminas\",\"https:\\\/\\\/x.com\\\/colabpucminas\",\"https:\\\/\\\/www.instagram.com\\\/colabpucminas\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/colab-puc-minas\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC14mKIqnnGCOgVr4DG6FPkA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#\\\/schema\\\/person\\\/86585f5b53a3550279327e4c1d56bac9\",\"name\":\"Yago Rabelo Marques\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0eda6ed7434a979896abf6a4c25473211b51a0ab1ab15e340d3658e91a44a69b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0eda6ed7434a979896abf6a4c25473211b51a0ab1ab15e340d3658e91a44a69b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0eda6ed7434a979896abf6a4c25473211b51a0ab1ab15e340d3658e91a44a69b?s=96&d=mm&r=g\",\"caption\":\"Yago Rabelo Marques\"},\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/author\\\/yagomarquezs03\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anonimato alimenta discurso de \u00f3dio nas m\u00eddias sociais - Colab","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/","og_locale":"pt_BR","og_type":"article","og_title":"Anonimato alimenta discurso de \u00f3dio nas m\u00eddias sociais - Colab","og_description":"Elei\u00e7\u00e3o de 2018 marcou virada da pol\u00edtica","og_url":"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/","og_site_name":"Colab","article_publisher":"https:\/\/www.facebook.com\/colabpucminas","article_published_time":"2025-09-25T18:44:06+00:00","article_modified_time":"2025-10-09T00:39:44+00:00","og_image":[{"width":1296,"height":675,"url":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Adobe-Express-file.webp","type":"image\/jpeg"}],"author":"Yago Rabelo Marques","twitter_card":"summary_large_image","twitter_creator":"@colabpucminas","twitter_site":"@colabpucminas","twitter_misc":{"Escrito por":"Yago Rabelo Marques","Est. tempo de leitura":"17 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/#article","isPartOf":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/"},"author":{"name":"Yago Rabelo Marques","@id":"https:\/\/blogfca.pucminas.br\/colab\/#\/schema\/person\/86585f5b53a3550279327e4c1d56bac9"},"headline":"Anonimato alimenta discurso de \u00f3dio nas m\u00eddias sociais","datePublished":"2025-09-25T18:44:06+00:00","dateModified":"2025-10-09T00:39:44+00:00","mainEntityOfPage":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/"},"wordCount":3370,"commentCount":1,"publisher":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/#organization"},"image":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/#primaryimage"},"thumbnailUrl":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Adobe-Express-file.webp","keywords":["bolsonaro","historia","Instagram","juventude","politica","Redes sociais","tik tok","twitter"],"articleSection":["Elei\u00e7\u00f5es","Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/","url":"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/","name":"Anonimato alimenta discurso de \u00f3dio nas m\u00eddias sociais - Colab","isPartOf":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/#primaryimage"},"image":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/#primaryimage"},"thumbnailUrl":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Adobe-Express-file.webp","datePublished":"2025-09-25T18:44:06+00:00","dateModified":"2025-10-09T00:39:44+00:00","breadcrumb":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/#primaryimage","url":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Adobe-Express-file.webp","contentUrl":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2025\/09\/Adobe-Express-file.webp","width":1296,"height":675,"caption":"Manifestante segura cartaz com a mensagem \u201cNo Hate\u201d durante protesto - Tim Pierce"},{"@type":"BreadcrumbList","@id":"https:\/\/blogfca.pucminas.br\/colab\/anonimato-alimenta-discurso-de-odio-nas-midias-sociais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blogfca.pucminas.br\/colab\/"},{"@type":"ListItem","position":2,"name":"Anonimato alimenta discurso de \u00f3dio nas m\u00eddias sociais"}]},{"@type":"WebSite","@id":"https:\/\/blogfca.pucminas.br\/colab\/#website","url":"https:\/\/blogfca.pucminas.br\/colab\/","name":"Colab","description":"Experimenta\u00e7\u00e3o, conte\u00fado e colabora\u00e7\u00e3o em Jornalismo Digital","publisher":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogfca.pucminas.br\/colab\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blogfca.pucminas.br\/colab\/#organization","name":"Colab :: Laborat\u00f3rio de Comunica\u00e7\u00e3o Digital da FCA \/ PUC Minas","url":"https:\/\/blogfca.pucminas.br\/colab\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogfca.pucminas.br\/colab\/#\/schema\/logo\/image\/","url":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2020\/03\/Avatar-Colab.jpg","contentUrl":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2020\/03\/Avatar-Colab.jpg","width":1682,"height":1682,"caption":"Colab :: Laborat\u00f3rio de Comunica\u00e7\u00e3o Digital da FCA \/ PUC Minas"},"image":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/colabpucminas","https:\/\/x.com\/colabpucminas","https:\/\/www.instagram.com\/colabpucminas\/","https:\/\/www.linkedin.com\/company\/colab-puc-minas","https:\/\/www.youtube.com\/channel\/UC14mKIqnnGCOgVr4DG6FPkA"]},{"@type":"Person","@id":"https:\/\/blogfca.pucminas.br\/colab\/#\/schema\/person\/86585f5b53a3550279327e4c1d56bac9","name":"Yago Rabelo Marques","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0eda6ed7434a979896abf6a4c25473211b51a0ab1ab15e340d3658e91a44a69b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0eda6ed7434a979896abf6a4c25473211b51a0ab1ab15e340d3658e91a44a69b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0eda6ed7434a979896abf6a4c25473211b51a0ab1ab15e340d3658e91a44a69b?s=96&d=mm&r=g","caption":"Yago Rabelo Marques"},"url":"https:\/\/blogfca.pucminas.br\/colab\/author\/yagomarquezs03\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/posts\/24539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/users\/115"}],"replies":[{"embeddable":true,"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/comments?post=24539"}],"version-history":[{"count":10,"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/posts\/24539\/revisions"}],"predecessor-version":[{"id":24784,"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/posts\/24539\/revisions\/24784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/media\/24557"}],"wp:attachment":[{"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/media?parent=24539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/categories?post=24539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/tags?post=24539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}