{"id":10839,"date":"2022-09-29T23:36:46","date_gmt":"2022-09-30T02:36:46","guid":{"rendered":"https:\/\/blogfca.pucminas.br\/colab\/?p=10839"},"modified":"2022-10-25T17:04:39","modified_gmt":"2022-10-25T20:04:39","slug":"confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente","status":"publish","type":"post","link":"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/","title":{"rendered":"Confira os planos de governo dos presidenci\u00e1veis: vote consciente!"},"content":{"rendered":"\n<p>No pr\u00f3ximo domingo, dia 2 de outubro, a popula\u00e7\u00e3o brasileira vai \u00e0s urnas escolher as pessoas que as representar\u00e3o tanto nos cargos eletivos do <a href=\"https:\/\/www.tre-pb.jus.br\/comunicacao\/noticias\/2022\/Setembro\/faltam-5-dias-2013-qual-a-diferenca-entre-candidatura-majoritaria-e-proporcional\" target=\"_blank\" rel=\"noreferrer noopener\">sistema majorit\u00e1rio<\/a> (governadores, senadores e presidente) quanto no proporcional (deputados estaduais e federais). Para ocupar o principal cargo do Poder Executivo, a Presid\u00eancia da Rep\u00fablica, as candidaturas apresentam aos eleitores os planos de governo. Neles os candidatos detalham o que pretendem fazer em cada setor de administra\u00e7\u00e3o p\u00fablica, durante a gest\u00e3o de quatro anos na presid\u00eancia do Brasil. Mas se voc\u00ea n\u00e3o sabe qual \u00e9 a import\u00e2ncia de um plano de governo e o como ele pode te ajudar a tomar decis\u00f5es, o Colab preparou este material para te ajudar. Aqui apresentamos as principais propostas de todos os candidatos que disputam a Presid\u00eancia em rela\u00e7\u00e3o \u00e0 cultura, economia, educa\u00e7\u00e3o, fome, sa\u00fade e seguran\u00e7a p\u00fablica. Confira os planos de governo dos presidenci\u00e1veis: vote consciente!<\/p>\n\n\n\n<p>Mas para quem ainda n\u00e3o sabe bem o que \u00e9 um plano de governo, a gente explica. Os planos s\u00e3o os documentos em que os candidatos a cargos do Executivo (prefeituras, governos estaduais e Presid\u00eancia) informam suas propostas e as pol\u00edticas p\u00fablicas que pretendem desenvolver se forem eleitos. Segundo o coordenador do N\u00facleo de Estudos Sociopol\u00edticos da PUC Minas (Nesp), Robson S\u00e1vio, os planos de governo s\u00e3o uma plataforma de propostas que todos os candidatos devem apresentar para que o eleitor tenha alguns crit\u00e9rios na hora de processar as escolhas. S\u00e3o indicativos de uma vis\u00e3o de mundo, uma vis\u00e3o de sociedade, de Estado, de pol\u00edtica p\u00fablica que os candidatos devem apresentar como a plataforma das suas a\u00e7\u00f5es, se eleitos. Devem conter qualquer vis\u00e3o do candidato e do partido acerca das prioridades que ter\u00e3o na gest\u00e3o do governo durante seu mandato. A apresenta\u00e7\u00e3o dos planos \u00e9 uma exig\u00eancia formal da Justi\u00e7a Eleitoral, mas n\u00e3o significa que h\u00e1 algum tipo de penaliza\u00e7\u00e3o quando o candidato eleito n\u00e3o cumpre aquilo que est\u00e1 no seu plano.<\/p>\n\n\n\n<p>O cidad\u00e3o precisa compreender a import\u00e2ncia do voto consciente no processo eleitoral e na democracia, pois, conforme Robson S\u00e1vio, as escolhas n\u00e3o se limitam simplesmente \u00e0 hora do voto. Acompanhar os planos efetivamente durante todo exerc\u00edcio do mandato do candidato eleito permite que o cidad\u00e3o tenha crit\u00e9rios para saber quais propostas foram ou n\u00e3o cumpridas por um candidato que demanda ou proponha a pr\u00f3pria reelei\u00e7\u00e3o. Al\u00e9m disso, \u00e9 fundamental na hora de eleger um novo candidato, do qual n\u00e3o se tem nenhum conhecimento.<\/p>\n\n\n\n<p>O coordenador do Nesp ainda diz ser bom recordar que, al\u00e9m do cidad\u00e3o individualmente, os grupos da sociedade civil e a m\u00eddia tamb\u00e9m podem avaliar se essas propostas est\u00e3o sendo implementadas. Robson S\u00e1vio explica que \u00f3rg\u00e3os de imprensa, por exemplo, t\u00eam feito avalia\u00e7\u00f5es ao final de cada mandato. Verificam quais foram aquelas promessas que constam nos planos de governo, as que foram ou n\u00e3o efetuadas, assim como a porcentagem de cumprimento daquelas metas. Funciona como uma esp\u00e9cie de contabilidade e uma forma de prestar contas \u00e0 pr\u00f3pria sociedade. &#8220;Porque os pr\u00f3prios candidatos n\u00e3o fazem isso.&#8221;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conhe\u00e7a as principais propostas em cada \u00e1rea<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Cultura<\/h2>\n\n\n\n<p>A cultura foi um dos setores mais afetados durante a pandemia. Segundo o <a href=\"https:\/\/www.ibge.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">IBGE<\/a>, em 2020 o n\u00famero de trabalhadores nessa \u00e1rea retraiu cerca de 11,2%. Mais de 600 mil vagas foram perdidas na \u00e1rea. Confira as principais propostas dos candidatos para o setor cultural.<\/p>\n\n\n\n<p>O candidato <strong>Ciro Gomes, do Partido Democr\u00e1tico Trabalhista (PDT)<\/strong>, pretende investir na democratiza\u00e7\u00e3o do acesso e na expans\u00e3o do consumo de bens e servi\u00e7os culturais. Estimular as manifesta\u00e7\u00f5es culturais que propiciam a inclus\u00e3o social e a cultura perif\u00e9rica de rua, como as dan\u00e7as, <em>gra\u00fbtes<\/em> e<em> slams<\/em>. O candidato incluiu nas propostas culturais a\u00e7\u00f5es mais voltadas \u00e0 educa\u00e7\u00e3o e acesso \u00e0 internet.<\/p>\n\n\n\n<p>O atual presidente, <strong>Jair Bolsonaro, do Partido Liberal (PL)<\/strong>, planeja ampliar e fortalecer a Pol\u00edtica Nacional de Cultura e informa que pretende maximizar o investimento na cultura brasileira, &#8220;valorizando e fortalecendo os nossos valores culturais&#8221;. Menciona triplicar a verba destinada a patrim\u00f4nio, mas n\u00e3o informa como isso ser\u00e1 viabilizado. <\/p>\n\n\n\n<p><strong>Luiz In\u00e1cio Lula da Silva, do Partido dos Trabalhadores (PT)<\/strong>, que vem liderando as pesquisas, diz em seu plano de governo que \u201ca cultura \u00e9 uma dimens\u00e3o estrat\u00e9gica do processo de reconstru\u00e7\u00e3o democr\u00e1tica do pa\u00eds e da retomada do desenvolvimento sustent\u00e1vel.\u201d Ele defende o direito \u00e0 cultura, com o fortalecimento das institui\u00e7\u00f5es culturais e a recomposi\u00e7\u00e3o do financiamento e do investimento.<\/p>\n\n\n\n<p><strong>Compare as propostas dos tr\u00eas primeiros colocados na \u00faltima pesquisa Ipec:<\/strong><\/p>\n\n\n<div class=\"n2-section-smartslider fitvidsignore  n2_clear\" data-ssid=\"39\"><div id=\"n2-ss-39-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-39\" data-creator=\"Smart Slider 3\" data-responsive=\"auto\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition  \"><div class=\"n2-ss-slider-wrapper-inside\">\n        <div class=\"n2-ss-slider-1 n2_ss__touch_element n2-ow\">\n            <div class=\"n2-ss-slider-2 n2-ow\">\n                                                <div class=\"n2-ss-slider-3 n2-ow\">\n\n                    <div class=\"n2-ss-slide-backgrounds n2-ow-all\"><div class=\"n2-ss-slide-background\" data-public-id=\"1\" data-mode=\"fill\"><div class=\"n2-ss-slide-background-image\" data-blur=\"0\" data-opacity=\"100\" data-x=\"50\" data-y=\"50\" data-alt=\"\" data-title=\"\"><picture class=\"skip-lazy\" data-skip-lazy=\"1\"><img decoding=\"async\" src=\"\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2022\/09\/1.jpg\" alt=\"\" title=\"\" loading=\"lazy\" class=\"skip-lazy\" data-skip-lazy=\"1\"><\/picture><\/div><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><div class=\"n2-ss-slide-background\" data-public-id=\"2\" data-mode=\"fill\" aria-hidden=\"true\"><div class=\"n2-ss-slide-background-image\" data-blur=\"0\" data-opacity=\"100\" data-x=\"50\" data-y=\"50\" data-alt=\"\" data-title=\"\"><picture class=\"skip-lazy\" data-skip-lazy=\"1\"><img decoding=\"async\" src=\"\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2022\/09\/2.jpg\" alt=\"\" title=\"\" loading=\"lazy\" class=\"skip-lazy\" data-skip-lazy=\"1\"><\/picture><\/div><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><div class=\"n2-ss-slide-background\" data-public-id=\"3\" data-mode=\"fill\" aria-hidden=\"true\"><div class=\"n2-ss-slide-background-image\" data-blur=\"0\" data-opacity=\"100\" data-x=\"50\" data-y=\"50\" data-alt=\"\" data-title=\"\"><picture class=\"skip-lazy\" data-skip-lazy=\"1\"><img decoding=\"async\" src=\"\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2022\/09\/3.jpg\" alt=\"\" title=\"\" loading=\"lazy\" class=\"skip-lazy\" data-skip-lazy=\"1\"><\/picture><\/div><div data-color=\"RGBA(255,255,255,0)\" style=\"background-color: RGBA(255,255,255,0);\" class=\"n2-ss-slide-background-color\"><\/div><\/div><\/div>                    <div class=\"n2-ss-slider-4 n2-ow\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1200 600\" data-related-device=\"desktopPortrait\" class=\"n2-ow n2-ss-preserve-size n2-ss-preserve-size--slider n2-ss-slide-limiter\"><\/svg><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"294\" data-slide-public-id=\"1\" data-title=\"1\" class=\"n2-ss-slide n2-ow  n2-ss-slide-294\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">1<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-9TNyzWvrE9PY\" data-sstype=\"slide\" data-pm=\"default\"><\/div><\/div><\/div><div data-slide-duration=\"0\" data-id=\"275\" data-slide-public-id=\"2\" aria-hidden=\"true\" data-title=\"2\" class=\"n2-ss-slide n2-ow  n2-ss-slide-275\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">2<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-7BFbG0i4Ank3\" data-sstype=\"slide\" data-pm=\"default\"><\/div><\/div><\/div><div data-slide-duration=\"0\" data-id=\"276\" data-slide-public-id=\"3\" aria-hidden=\"true\" data-title=\"3\" class=\"n2-ss-slide n2-ow  n2-ss-slide-276\"><div role=\"note\" class=\"n2-ss-slide--focus\" tabindex=\"-1\">3<\/div><div class=\"n2-ss-layers-container n2-ss-slide-limiter n2-ow\"><div class=\"n2-ss-layer n2-ow n-uc-8Z9PmPBfQJFs\" data-sstype=\"slide\" data-pm=\"default\"><\/div><\/div><\/div>                    <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"n2-ss-slider-controls n2-ss-slider-controls-absolute-left-center\"><div style=\"--widget-offset:15px;\" class=\"n2-ss-widget nextend-arrow n2-ow-all nextend-arrow-previous  nextend-arrow-animated-fade\" data-hide-mobileportrait=\"1\" id=\"n2-ss-39-arrow-previous\" role=\"button\" aria-label=\"previous arrow\" tabindex=\"0\"><img loading=\"lazy\" decoding=\"async\" width=\"32\" height=\"32\" class=\"skip-lazy\" data-skip-lazy=\"1\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMzIiIGhlaWdodD0iMzIiIHZpZXdCb3g9IjAgMCAzMiAzMiIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIj4KICAgIDxwYXRoIGQ9Ik0xMS40MzMgMTUuOTkyTDIyLjY5IDUuNzEyYy4zOTMtLjM5LjM5My0xLjAzIDAtMS40Mi0uMzkzLS4zOS0xLjAzLS4zOS0xLjQyMyAwbC0xMS45OCAxMC45NGMtLjIxLjIxLS4zLjQ5LS4yODUuNzYtLjAxNS4yOC4wNzUuNTYuMjg0Ljc3bDExLjk4IDEwLjk0Yy4zOTMuMzkgMS4wMy4zOSAxLjQyNCAwIC4zOTMtLjQuMzkzLTEuMDMgMC0xLjQybC0xMS4yNTctMTAuMjkiCiAgICAgICAgICBmaWxsPSIjZmZmZmZmIiBvcGFjaXR5PSIwLjgiIGZpbGwtcnVsZT0iZXZlbm9kZCIvPgo8L3N2Zz4=\" alt=\"previous arrow\"><\/div><\/div><div class=\"n2-ss-slider-controls n2-ss-slider-controls-absolute-right-center\"><div style=\"--widget-offset:15px;\" class=\"n2-ss-widget nextend-arrow n2-ow-all nextend-arrow-next  nextend-arrow-animated-fade\" data-hide-mobileportrait=\"1\" id=\"n2-ss-39-arrow-next\" role=\"button\" aria-label=\"next arrow\" tabindex=\"0\"><img loading=\"lazy\" decoding=\"async\" width=\"32\" height=\"32\" class=\"skip-lazy\" data-skip-lazy=\"1\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMzIiIGhlaWdodD0iMzIiIHZpZXdCb3g9IjAgMCAzMiAzMiIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIj4KICAgIDxwYXRoIGQ9Ik0xMC43MjIgNC4yOTNjLS4zOTQtLjM5LTEuMDMyLS4zOS0xLjQyNyAwLS4zOTMuMzktLjM5MyAxLjAzIDAgMS40MmwxMS4yODMgMTAuMjgtMTEuMjgzIDEwLjI5Yy0uMzkzLjM5LS4zOTMgMS4wMiAwIDEuNDIuMzk1LjM5IDEuMDMzLjM5IDEuNDI3IDBsMTIuMDA3LTEwLjk0Yy4yMS0uMjEuMy0uNDkuMjg0LS43Ny4wMTQtLjI3LS4wNzYtLjU1LS4yODYtLjc2TDEwLjcyIDQuMjkzeiIKICAgICAgICAgIGZpbGw9IiNmZmZmZmYiIG9wYWNpdHk9IjAuOCIgZmlsbC1ydWxlPSJldmVub2RkIi8+Cjwvc3ZnPg==\" alt=\"next arrow\"><\/div><\/div><\/div><\/div><ss3-loader><\/ss3-loader><\/div><\/div><div class=\"n2_clear\"><\/div><\/div>\n\n\n<p><\/p>\n\n\n\n<p><strong>Jos\u00e9 Maria Eymael (Constituinte Eymael), da Democracia Crist\u00e3 (DC)<\/strong>, promete \u201cpromover a cultura atrav\u00e9s de a\u00e7\u00f5es de governo, pol\u00edticas de incentivo e parceria com a iniciativa privada.\u201d Eymael pretende:<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Visa a cria\u00e7\u00e3o de novos espa\u00e7os culturais e a produ\u00e7\u00e3o cultural nas suas v\u00e1rias manifesta\u00e7\u00f5es.<\/li><li>Valorizar a diversidade e a pluralidade no financiamento de atividades culturais.<\/li><li> Resgate e valoriza\u00e7\u00e3o da cultura e da identidade nacional.<\/li><\/ul>\n\n\n\n<p><strong>Felipe D&#8217;\u00e1vila, do partido Novo<\/strong>, diz em seu plano de governo acreditar em \u201cum Brasil din\u00e2mico, tendo a cultura, turismo e economia criativa como motores do desenvolvimento.\u201d Felipe diz que a pol\u00edtica p\u00fablica de cultura est\u00e1 vinculada ao conceito de liberdade e o acesso \u00e0 produ\u00e7\u00e3o art\u00edstica n\u00e3o pode ser um privil\u00e9gio de poucos. Felipe pretende:<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Criar o Conselho Nacional de Cultura<\/li><li>Inserir a cultura no processo educacional.<\/li><li>Elabora\u00e7\u00e3o de um \u201cAtlas da Criatividade do Brasil\u201d que identifique o potencial de desenvolvimento dos setores criativos e induz \u00e0 conscientiza\u00e7\u00e3o dos governos locais e da popula\u00e7\u00e3o sobre a import\u00e2ncia e o potencial econ\u00f4mico desse setor.<\/li><li>Promover o aproveitamento econ\u00f4mico do patrim\u00f4nio natural para fins de turismo e de lazer, conciliando a conserva\u00e7\u00e3o ambiental.<\/li><\/ul>\n\n\n\n<p><strong>L\u00e9o P\u00e9ricles, da Unidade Popular (UP)<\/strong>, d\u00e1 enfoque na defesa e incentivo \u00e0 cultura nacional e popular e em uma nacionaliza\u00e7\u00e3o de todas as companhias gravadoras de m\u00fasica e produtoras de filmes. L\u00e9o pretende:<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Favorecer os setores culturais e de entretenimento.<\/li><li>Democratizar os meios de comunica\u00e7\u00e3o e dos aparelhos p\u00fablicos culturais (teatros, museus, galerias e centros de conven\u00e7\u00f5es e eventos).<\/li><li>Implementar uma ind\u00fastria cinematogr\u00e1fica nacional e cria\u00e7\u00e3o de provedores de conte\u00fado de dom\u00ednio p\u00fablico e infraestrutura aberta, al\u00e9m de alternativas de redes sociais sob controle popular<\/li><\/ul>\n\n\n\n<p><strong>Padre Kelmon, do Partido Trabalhista Brasileiro (PTB)<\/strong>, diz que o partido luta pelo constante aprimoramento profissional, educacional e cultural da classe trabalhadora e pela efetiva extens\u00e3o de seus direitos. Mas n\u00e3o especifica como far\u00e1 para mudar essa realidade.<\/p>\n\n\n\n<p><strong>Simone Tebet, do Movimento Democr\u00e1tico Brasileiro (MDB)<\/strong>, diz que \u201ca cultura voltar\u00e1 a ser tratada com o status, a aten\u00e7\u00e3o e a import\u00e2ncia que merece.\u201d Para isso, pretende:<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Recriar um minist\u00e9rio espec\u00edfico, para articular pol\u00edticas com estados e munic\u00edpios como estrat\u00e9gia de desenvolvimento, cidadania e fortalecimento da economia criativa.<\/li><li>Recriar o Minist\u00e9rio da Cultura, recuperando o status, a aten\u00e7\u00e3o e a import\u00e2ncia que a \u00e1rea merece.<\/li><li>Fortalecer leis de incentivo \u00e0 cultura, como a lei Rouanet, a lei Aldir Blanc e a lei do Audiovisual.<\/li><li>Assegurar que as pessoas com defici\u00eancia possam ter acesso a bens culturais em formatos acess\u00edveis.<\/li><li>Valorizar o patrim\u00f4nio cultural e hist\u00f3rico e garantir sua preserva\u00e7\u00e3o e manuten\u00e7\u00e3o.<\/li><\/ul>\n\n\n\n<p><strong>Sofia Manzano, do Partido Comunista Brasileiro (PCB)<\/strong>, afirma que o Brasil \u00e9 um pa\u00eds que possui uma enorme diversidade cultural, resultado da mescla de cultura de v\u00e1rios povos que constituem a sociedade brasileira. Al\u00e9m disso, possui uma rede de comunica\u00e7\u00e3o integrada que cobre todo o pa\u00eds. No entanto, seu programa diz que essa imensa potencialidade foi apropriada pelas classes dominantes e manipulada pelos meios de comunica\u00e7\u00e3o, que distorcem e alienam a cultura de massa difundida diariamente. Para reverter essa conjuntura, ela prop\u00f5e:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Promover uma ampla pol\u00edtica cultural que abra espa\u00e7o para a criatividade, experimenta\u00e7\u00f5es e as mais diversas express\u00f5es art\u00edsticas e busque um resgate da cultura popular e de massas.<\/li><li>Respaldar a constru\u00e7\u00e3o de um amplo movimento cultural com capacidade de inovar na est\u00e9tica e no panorama cultural brasileiro, buscando romper com os interesses dos monop\u00f3lios dominantes nacionais e internacionais.<\/li><li>Desenvolver uma pol\u00edtica de constru\u00e7\u00e3o em massa de espa\u00e7os culturais nos bairros, como forma de garantir amplo acesso da popula\u00e7\u00e3o \u00e0s artes e de incentivar a emerg\u00eancia de novos talentos culturais nas regi\u00f5es populares.<\/li><\/ul>\n\n\n\n<p>O programa de <strong>Soraya Thronicke, do Uni\u00e3o Brasil<\/strong>, afirma que o impacto negativo da pandemia sobre toda a economia nacional foi imenso. Mas a crise que se abateu sobre o setor cultural nacional foi marcada pela indefini\u00e7\u00e3o de uma estrat\u00e9gia pol\u00edtica que permitisse a economia cultural superar as dificuldades efetivamente. Os preju\u00edzos financeiros foram imensos e atingiram v\u00e1rios segmentos do setor cultural. O governo federal demorou muito a socorrer o setor. Essa demora causou enormes preju\u00edzos e desempregos significativos. A candidata pretende:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Implementar um plano emergencial para capacitar tecnologicamente os profissionais da cultura que t\u00eam dificuldade de acessar \u00e0s novas formas de produ\u00e7\u00e3o e consumo de produtos e servi\u00e7os culturais.<\/li><li>Fortalecer as manifesta\u00e7\u00f5es culturais t\u00edpicas.<\/li><li>Regulamentar o Sistema Brasileiro de Cultura.<\/li><li>Regulamentar e gerenciar estrategicamente o fundo Paulo Gustavo.<\/li><li>Estabelecer parcerias com Minist\u00e9rio do Turismo e prefeituras para promover o Turismo Cultural em todo o Brasil.<\/li><li>Fortalecer a Funarte, ampliando sua atua\u00e7\u00e3o em todo o territ\u00f3rio nacional.<\/li><\/ul>\n\n\n\n<p><strong>Vera L\u00facia, do Partido Socialista dos Trabalhadores Unificado (PSTU)<\/strong>, diz em seu plano de governo que a cria\u00e7\u00e3o cultural tem sido severamente atacada e restringida. Tanto pela repress\u00e3o do governo de ultradireita de Bolsonaro, como pelos limites impostos pela grande m\u00eddia e a estrutura cultural burguesa. Ela defende:<br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Plena liberdade de cria\u00e7\u00e3o cultural e o fim de todos os tipos de censura.<\/li><li>Apoio estatal para a cria\u00e7\u00e3o e difus\u00e3o da cultura popular musical, po\u00e9tica, pl\u00e1stica, do teatro e cinema.<\/li><li>Constru\u00e7\u00e3o de espa\u00e7os art\u00edsticos nos bairros populares que permitam a express\u00e3o e desenvolvimento de nossos artistas e da juventude.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/blogfca.pucminas.br\/colab\/propostas-do-setor-de-economia-dos-candidatos-a-presidencia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Economia<\/a><\/h2>\n\n\n\n<p>Devido a pandemia da covid-19, mais gente perdeu seus empregos.  Conforme o IBGE, aproximadamente tr\u00eas em cada dez desempregados permanecem em busca por trabalho h\u00e1 mais de dois anos. Outra problem\u00e1tica tem sido o aumento constante da infla\u00e7\u00e3o. Apesar da recente defla\u00e7\u00e3o, em 2021 a infla\u00e7\u00e3o foi de 5,1%, metade do \u00edndice de pre\u00e7os ao consumidor cheio no ano, que foi de 10,06%. No resultado acumulado em julho de 2022, a infla\u00e7\u00e3o de servi\u00e7os subiu 8,87%, sendo a maior taxa para o per\u00edodo de um ano desde junho de 2014 (9,20%). Em agosto de 2022 o IPCA registrou queda de 0,73. Assim, temas como emprego, desigualdade, infla\u00e7\u00e3o, piso do sal\u00e1rio m\u00ednimo, acordo com bancos e recupera\u00e7\u00e3o da crise financeira se tornaram essenciais para escolher o candidato. <a href=\"https:\/\/blogfca.pucminas.br\/colab\/propostas-do-setor-de-economia-dos-candidatos-a-presidencia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Confira quais s\u00e3o as propostas de cada candidato.&nbsp;<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br><a href=\"https:\/\/blogfca.pucminas.br\/colab\/propostas-do-setor-da-educacao-dos-candidatos-a-presidencia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Educa\u00e7\u00e3o<\/a><\/h2>\n\n\n\n<p>Em 2020, ano em que a pandemia de covid-19 se alastrou no Brasil e no mundo, o n\u00famero de crian\u00e7as e adolescentes que n\u00e3o t\u00eam acesso \u00e0 educa\u00e7\u00e3o foi de 5,1 milh\u00f5es, sendo que em 2019 a quantia somava 1,1 milh\u00e3o, de acordo com um estudo feito pelo <a href=\"https:\/\/www.unicef.org\/brazil\/relatorios\/cenario-da-exclusao-escolar-no-brasil\">Fundo das Na\u00e7\u00f5es Unidas para a Inf\u00e2ncia (Unicef)<\/a>.<\/p>\n\n\n\n<p>De acordo com a <a href=\"https:\/\/educa.ibge.gov.br\/jovens\/conheca-o-brasil\/populacao\/18317-educacao.html#:~:text=Tamb%C3%A9m%20em%202019%2C%2046%2C6,4%25%2C%20o%20superior%20completo.\">Pesquisa Nacional por Amostra de Domic\u00edlios Cont\u00ednua (PNAD Cont\u00ednua) 2019<\/a>, no Brasil, 6,6% das pessoas de 15 anos ou mais s\u00e3o analfabetas, totalizando 11 milh\u00f5es de analfabetos.<a href=\"https:\/\/blogfca.pucminas.br\/colab\/propostas-do-setor-da-educacao-dos-candidatos-a-presidencia\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Confira as propostas dos candidatos para esse setor.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br><a href=\"https:\/\/blogfca.pucminas.br\/colab\/propostas-do-setor-da-fome-e-seguranca-alimentar-dos-candidatos-a-presidencia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fome e seguran\u00e7a alimentar<\/a><\/h2>\n\n\n\n<p>Em 2014 o Brasil foi retirado do mapa da fome feito pela Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU). No entanto, a desigualdade social j\u00e1 existente e o aumento da infla\u00e7\u00e3o durante a pandemia, acentuaram os casos de fam\u00edlias em situa\u00e7\u00e3o de inseguran\u00e7a alimentar. De acordo com a Pesquisa em Soberania e Seguran\u00e7a Alimentar e Nutricional (Rede Penssan), realizada em 2022, a fome \u00e9 um problema que atinge 33,1 milh\u00f5es de brasileiros. <a href=\"https:\/\/blogfca.pucminas.br\/colab\/propostas-do-setor-da-fome-e-seguranca-alimentar-dos-candidatos-a-presidencia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Confira como cada um dos candidatos \u00e0 Presid\u00eancia pretende lidar com este problema.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/blogfca.pucminas.br\/colab\/propostas-do-setor-da-saude-dos-candidatos-a-presidencia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sa\u00fade<\/a><\/h2>\n\n\n\n<p>A \u00e1rea da sa\u00fade foi o setor que mais sofreu durante o per\u00edodo pand\u00eamico, envolvendo sesde a recusa inicial da<a href=\"https:\/\/g1.globo.com\/politica\/blog\/octavio-guedes\/post\/2021\/04\/27\/cpi-da-covid-governo-bolsonaro-recusou-11-vezes-ofertas-para-compras-de-vacina.ghtml\" target=\"_blank\" rel=\"noreferrer noopener\"> compra de vacinas pelo Governo Federal <\/a>at\u00e9 a <a href=\"https:\/\/informe.ensp.fiocruz.br\/noticias\/50926\" target=\"_blank\" rel=\"noreferrer noopener\">falta de oxig\u00eanio em Manaus<\/a>. Em 2021, foi divulgada a <a href=\"https:\/\/agenciabrasil.ebc.com.br\/saude\/noticia\/2021-11\/pesquisa-80-dos-brasileiros-estao-preocupados-com-acesso-saude\" target=\"_blank\" rel=\"noreferrer noopener\">pesquisa da Associa\u00e7\u00e3o Nacional das Administradoras de Benef\u00edcio para o Instituto Bateiah Estrat\u00e9gia e Reputa\u00e7\u00e3o<\/a>. De acordo com o levantamento, a sa\u00fade \u00e9 uma das principais preocupa\u00e7\u00f5es de 81% dos brasileiros, principalmente entre aqueles que possuem renda de at\u00e9 cinco sal\u00e1rios m\u00ednimos. <a href=\"https:\/\/blogfca.pucminas.br\/colab\/propostas-do-setor-da-saude-dos-candidatos-a-presidencia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Confira as principais propostas dos candidatos para o setor da sa\u00fade, come\u00e7ando com os tr\u00eas primeiros colocados nas pesquisas.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><br><a href=\"https:\/\/blogfca.pucminas.br\/colab\/propostas-do-setor-da-seguranca-publica-dos-candidatos-a-presidencia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Seguran\u00e7a P\u00fablica<\/a><\/h2>\n\n\n\n<p>Seguran\u00e7a p\u00fablica \u00e9 um dos principais temas de campanha nestas elei\u00e7\u00f5es, e tamb\u00e9m \u00e9 uma das pautas mais cobradas pelos eleitores. De acordo com dados do SIM, em <a href=\"https:\/\/noticias.uol.com.br\/colunas\/carlos-madeiro\/2022\/07\/15\/mortes-por-arma-de-fogo-de-mao-sobem-em-meio-a-queda-de-homicidios-no-pais.amp.htm\" target=\"_blank\" rel=\"noreferrer noopener\">conte\u00fado divulgado pelo UOL<\/a>, mesmo a taxa de homic\u00eddios tendo diminu\u00eddo, a morte por arma de fogo aumentou 24% em 2021 perante a 2020. Com isso, \u00e9 importante analisar os projetos de cada candidato \u00e0 Presid\u00eancia para seguran\u00e7a p\u00fablica. <a href=\"https:\/\/blogfca.pucminas.br\/colab\/propostas-do-setor-da-seguranca-publica-dos-candidatos-a-presidencia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Clique e confira as principais propostas para esse setor.<\/a><\/p>\n\n\n\n<pre class=\"wp-block-verse\"><em>Conte\u00fado produzido por Anna Paim, Bianka Reinhardt, Fernanda Bertollini, Giovanna Minarrini, Isabella Alvim e Maria Lu\u00edza Rabello.<\/em><\/pre>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Colab apresenta aqui as principais propostas de todos os candidatos \u00e0 Presid\u00eancia da Rep\u00fablica para auxiliar na decis\u00e3o do voto<\/p>\n","protected":false},"author":36,"featured_media":10956,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[7,11],"tags":[628,665,1236,359,174,695,323,1046,1047,1230,210,1232,254],"class_list":["post-10839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eleicoes","category-politica","tag-bolsonaro","tag-candidatos","tag-ciro","tag-colab","tag-cultura","tag-economia","tag-educacao","tag-eleicoes-2022","tag-lula","tag-planodegoverno","tag-politica","tag-presidencia","tag-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Confira os planos de governo dos presidenci\u00e1veis: vote consciente! - Colab<\/title>\n<meta name=\"description\" content=\"Veja as principais propostas dos candidatos para a cultura, economia, educa\u00e7\u00e3o, fome, sa\u00fade e seguran\u00e7a p\u00fablica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confira os planos de governo dos presidenci\u00e1veis: vote consciente! - Colab\" \/>\n<meta property=\"og:description\" content=\"Veja as principais propostas dos candidatos para a cultura, economia, educa\u00e7\u00e3o, fome, sa\u00fade e seguran\u00e7a p\u00fablica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/\" \/>\n<meta property=\"og:site_name\" content=\"Colab\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/colabpucminas\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-30T02:36:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-25T20:04:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2022\/09\/Serie-Eleicoes-169-1200-\u00d7-600-px-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernanda Bertollini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@colabpucminas\" \/>\n<meta name=\"twitter:site\" content=\"@colabpucminas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernanda Bertollini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\\\/\"},\"author\":{\"name\":\"Fernanda Bertollini\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#\\\/schema\\\/person\\\/d9d2cef4e9bf5a12ffe7f204f6415c14\"},\"headline\":\"Confira os planos de governo dos presidenci\u00e1veis: vote consciente!\",\"datePublished\":\"2022-09-30T02:36:46+00:00\",\"dateModified\":\"2022-10-25T20:04:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\\\/\"},\"wordCount\":2312,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Serie-Eleicoes-169-1200-\u00d7-600-px-1.jpg\",\"keywords\":[\"bolsonaro\",\"candidatos\",\"ciro\",\"colab\",\"cultura\",\"economia\",\"educa\u00e7\u00e3o\",\"elei\u00e7\u00f5es 2022\",\"lula\",\"planodegoverno\",\"pol\u00edtica\",\"presid\u00eancia\",\"sa\u00fade\"],\"articleSection\":[\"Elei\u00e7\u00f5es\",\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\\\/\",\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\\\/\",\"name\":\"Confira os planos de governo dos presidenci\u00e1veis: vote consciente! - Colab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Serie-Eleicoes-169-1200-\u00d7-600-px-1.jpg\",\"datePublished\":\"2022-09-30T02:36:46+00:00\",\"dateModified\":\"2022-10-25T20:04:39+00:00\",\"description\":\"Veja as principais propostas dos candidatos para a cultura, economia, educa\u00e7\u00e3o, fome, sa\u00fade e seguran\u00e7a p\u00fablica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Serie-Eleicoes-169-1200-\u00d7-600-px-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Serie-Eleicoes-169-1200-\u00d7-600-px-1.jpg\",\"width\":1200,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confira os planos de governo dos presidenci\u00e1veis: vote consciente!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#website\",\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/\",\"name\":\"Colab\",\"description\":\"Experimenta\u00e7\u00e3o, conte\u00fado e colabora\u00e7\u00e3o em Jornalismo Digital\",\"publisher\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#organization\",\"name\":\"Colab :: Laborat\u00f3rio de Comunica\u00e7\u00e3o Digital da FCA \\\/ PUC Minas\",\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Avatar-Colab.jpg\",\"contentUrl\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Avatar-Colab.jpg\",\"width\":1682,\"height\":1682,\"caption\":\"Colab :: Laborat\u00f3rio de Comunica\u00e7\u00e3o Digital da FCA \\\/ PUC Minas\"},\"image\":{\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/colabpucminas\",\"https:\\\/\\\/x.com\\\/colabpucminas\",\"https:\\\/\\\/www.instagram.com\\\/colabpucminas\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/colab-puc-minas\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC14mKIqnnGCOgVr4DG6FPkA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/#\\\/schema\\\/person\\\/d9d2cef4e9bf5a12ffe7f204f6415c14\",\"name\":\"Fernanda Bertollini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/37e81963e4721565633399f6236012be8bb44e8e319abf3c6c4719e9263a9956?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/37e81963e4721565633399f6236012be8bb44e8e319abf3c6c4719e9263a9956?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/37e81963e4721565633399f6236012be8bb44e8e319abf3c6c4719e9263a9956?s=96&d=mm&r=g\",\"caption\":\"Fernanda Bertollini\"},\"url\":\"https:\\\/\\\/blogfca.pucminas.br\\\/colab\\\/author\\\/fbertollini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confira os planos de governo dos presidenci\u00e1veis: vote consciente! - Colab","description":"Veja as principais propostas dos candidatos para a cultura, economia, educa\u00e7\u00e3o, fome, sa\u00fade e seguran\u00e7a p\u00fablica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/","og_locale":"pt_BR","og_type":"article","og_title":"Confira os planos de governo dos presidenci\u00e1veis: vote consciente! - Colab","og_description":"Veja as principais propostas dos candidatos para a cultura, economia, educa\u00e7\u00e3o, fome, sa\u00fade e seguran\u00e7a p\u00fablica.","og_url":"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/","og_site_name":"Colab","article_publisher":"https:\/\/www.facebook.com\/colabpucminas","article_published_time":"2022-09-30T02:36:46+00:00","article_modified_time":"2022-10-25T20:04:39+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2022\/09\/Serie-Eleicoes-169-1200-\u00d7-600-px-1.jpg","type":"image\/jpeg"}],"author":"Fernanda Bertollini","twitter_card":"summary_large_image","twitter_creator":"@colabpucminas","twitter_site":"@colabpucminas","twitter_misc":{"Escrito por":"Fernanda Bertollini","Est. tempo de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/#article","isPartOf":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/"},"author":{"name":"Fernanda Bertollini","@id":"https:\/\/blogfca.pucminas.br\/colab\/#\/schema\/person\/d9d2cef4e9bf5a12ffe7f204f6415c14"},"headline":"Confira os planos de governo dos presidenci\u00e1veis: vote consciente!","datePublished":"2022-09-30T02:36:46+00:00","dateModified":"2022-10-25T20:04:39+00:00","mainEntityOfPage":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/"},"wordCount":2312,"commentCount":0,"publisher":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/#organization"},"image":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/#primaryimage"},"thumbnailUrl":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2022\/09\/Serie-Eleicoes-169-1200-\u00d7-600-px-1.jpg","keywords":["bolsonaro","candidatos","ciro","colab","cultura","economia","educa\u00e7\u00e3o","elei\u00e7\u00f5es 2022","lula","planodegoverno","pol\u00edtica","presid\u00eancia","sa\u00fade"],"articleSection":["Elei\u00e7\u00f5es","Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/","url":"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/","name":"Confira os planos de governo dos presidenci\u00e1veis: vote consciente! - Colab","isPartOf":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/#primaryimage"},"image":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/#primaryimage"},"thumbnailUrl":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2022\/09\/Serie-Eleicoes-169-1200-\u00d7-600-px-1.jpg","datePublished":"2022-09-30T02:36:46+00:00","dateModified":"2022-10-25T20:04:39+00:00","description":"Veja as principais propostas dos candidatos para a cultura, economia, educa\u00e7\u00e3o, fome, sa\u00fade e seguran\u00e7a p\u00fablica.","breadcrumb":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/#primaryimage","url":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2022\/09\/Serie-Eleicoes-169-1200-\u00d7-600-px-1.jpg","contentUrl":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2022\/09\/Serie-Eleicoes-169-1200-\u00d7-600-px-1.jpg","width":1200,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/blogfca.pucminas.br\/colab\/confira-os-planos-de-governo-dos-presidenciaveis-vote-consciente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/blogfca.pucminas.br\/colab\/"},{"@type":"ListItem","position":2,"name":"Confira os planos de governo dos presidenci\u00e1veis: vote consciente!"}]},{"@type":"WebSite","@id":"https:\/\/blogfca.pucminas.br\/colab\/#website","url":"https:\/\/blogfca.pucminas.br\/colab\/","name":"Colab","description":"Experimenta\u00e7\u00e3o, conte\u00fado e colabora\u00e7\u00e3o em Jornalismo Digital","publisher":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogfca.pucminas.br\/colab\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/blogfca.pucminas.br\/colab\/#organization","name":"Colab :: Laborat\u00f3rio de Comunica\u00e7\u00e3o Digital da FCA \/ PUC Minas","url":"https:\/\/blogfca.pucminas.br\/colab\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/blogfca.pucminas.br\/colab\/#\/schema\/logo\/image\/","url":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2020\/03\/Avatar-Colab.jpg","contentUrl":"https:\/\/blogfca.pucminas.br\/colab\/wp-content\/uploads\/2020\/03\/Avatar-Colab.jpg","width":1682,"height":1682,"caption":"Colab :: Laborat\u00f3rio de Comunica\u00e7\u00e3o Digital da FCA \/ PUC Minas"},"image":{"@id":"https:\/\/blogfca.pucminas.br\/colab\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/colabpucminas","https:\/\/x.com\/colabpucminas","https:\/\/www.instagram.com\/colabpucminas\/","https:\/\/www.linkedin.com\/company\/colab-puc-minas","https:\/\/www.youtube.com\/channel\/UC14mKIqnnGCOgVr4DG6FPkA"]},{"@type":"Person","@id":"https:\/\/blogfca.pucminas.br\/colab\/#\/schema\/person\/d9d2cef4e9bf5a12ffe7f204f6415c14","name":"Fernanda Bertollini","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/37e81963e4721565633399f6236012be8bb44e8e319abf3c6c4719e9263a9956?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/37e81963e4721565633399f6236012be8bb44e8e319abf3c6c4719e9263a9956?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/37e81963e4721565633399f6236012be8bb44e8e319abf3c6c4719e9263a9956?s=96&d=mm&r=g","caption":"Fernanda Bertollini"},"url":"https:\/\/blogfca.pucminas.br\/colab\/author\/fbertollini\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/posts\/10839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/comments?post=10839"}],"version-history":[{"count":18,"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/posts\/10839\/revisions"}],"predecessor-version":[{"id":11160,"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/posts\/10839\/revisions\/11160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/media\/10956"}],"wp:attachment":[{"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/media?parent=10839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/categories?post=10839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogfca.pucminas.br\/colab\/wp-json\/wp\/v2\/tags?post=10839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}